{"id":8090,"date":"2025-10-17T07:07:35","date_gmt":"2025-10-17T05:07:35","guid":{"rendered":"https:\/\/fimif.edu.al\/?p=8090"},"modified":"2025-10-17T10:38:28","modified_gmt":"2025-10-17T08:38:28","slug":"njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte","status":"publish","type":"post","link":"https:\/\/fimif.edu.al\/en\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/","title":{"rendered":"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Master i Shkencave ne Inxhinieri Matematike<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/ShListat-e-Fituesve-IM_MSH0095.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of ShListat e Fituesve IM_MSH0095.\"><\/object><a id=\"wp-block-file--media-a30779f1-8978-4731-90dd-0a24cc4bafe9\" href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/ShListat-e-Fituesve-IM_MSH0095.pdf\">ShListat e Fituesve IM_MSH0095<\/a><a href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/ShListat-e-Fituesve-IM_MSH0095.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-a30779f1-8978-4731-90dd-0a24cc4bafe9\">Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Master i Shkencave ne Inxhinieri Matematike ne Aktuaristike<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/IM-Renditja-e-aplikanteve_Cikli_II_2025-2026-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of IM Renditja e  aplikanteve_Cikli_II_2025-2026 (1).\"><\/object><a id=\"wp-block-file--media-d5c68451-a1a4-40cc-aafa-e199b6b5f181\" href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/IM-Renditja-e-aplikanteve_Cikli_II_2025-2026-1.pdf\">IM Renditja e  aplikanteve_Cikli_II_2025-2026 (1)<\/a><a href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/IM-Renditja-e-aplikanteve_Cikli_II_2025-2026-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-d5c68451-a1a4-40cc-aafa-e199b6b5f181\">Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Master Profesional ne Analiza Sistemesh<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-IM_MP_Analiza-Sistemesh0094.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of Listat e Fituesve IM_MP_Analiza Sistemesh0094.\"><\/object><a id=\"wp-block-file--media-7010cd17-a73a-4c97-bb78-b09648f97f96\" href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-IM_MP_Analiza-Sistemesh0094.pdf\">Listat e Fituesve IM_MP_Analiza Sistemesh0094<\/a><a href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-IM_MP_Analiza-Sistemesh0094.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-7010cd17-a73a-4c97-bb78-b09648f97f96\">Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Master i Shkencave ne Inxhinieri Fizike- Profili Inxhinier Fizike<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-MSH_IF_IF.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of Listat e Fituesve MSH_IF_IF.\"><\/object><a id=\"wp-block-file--media-65527a11-6054-4236-9f76-5575263ae596\" href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-MSH_IF_IF.pdf\">Listat e Fituesve MSH_IF_IF<\/a><a href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-MSH_IF_IF.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-65527a11-6054-4236-9f76-5575263ae596\">Download<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Master i Shkencave ne Inxhinieri Fizike- Profili Fizikan Mjekesor<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-MSH_IF_FM.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of Listat e Fituesve MSH_IF_FM.\"><\/object><a id=\"wp-block-file--media-6987ecee-18ec-42d2-a6c5-dab2802d7a6a\" href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-MSH_IF_FM.pdf\">Listat e Fituesve MSH_IF_FM<\/a><a href=\"https:\/\/fimif.edu.al\/wp-content\/uploads\/2025\/10\/Listat-e-Fituesve-MSH_IF_FM.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-6987ecee-18ec-42d2-a6c5-dab2802d7a6a\">Download<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Master i Shkencave ne Inxhinieri Matematike Master i Shkencave ne Inxhinieri Matematike ne Aktuaristike Master Profesional ne Analiza Sistemesh Master i Shkencave ne Inxhinieri Fizike- Profili Inxhinier Fizike Master i Shkencave ne Inxhinieri Fizike- Profili Fizikan Mjekesor<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8090","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026 - Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fimif.edu.al\/en\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026 - Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike\" \/>\n<meta property=\"og:description\" content=\"Master i Shkencave ne Inxhinieri Matematike Master i Shkencave ne Inxhinieri Matematike ne Aktuaristike Master Profesional ne Analiza Sistemesh Master i Shkencave ne Inxhinieri Fizike- Profili Inxhinier Fizike Master i Shkencave ne Inxhinieri Fizike- Profili Fizikan Mjekesor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fimif.edu.al\/en\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/\" \/>\n<meta property=\"og:site_name\" content=\"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Departamenti-i-Inxhinierise-Matematike-FIMIF-UPT-100077435994252\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T05:07:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T08:38:28+00:00\" \/>\n<meta name=\"author\" content=\"Gerta Lame\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerta Lame\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/\"},\"author\":{\"name\":\"Gerta Lame\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#\\\/schema\\\/person\\\/771075414e038199af3802af30f13da3\"},\"headline\":\"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026\",\"datePublished\":\"2025-10-17T05:07:35+00:00\",\"dateModified\":\"2025-10-17T08:38:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/\",\"url\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/\",\"name\":\"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026 - Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#website\"},\"datePublished\":\"2025-10-17T05:07:35+00:00\",\"dateModified\":\"2025-10-17T08:38:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fimif.edu.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#website\",\"url\":\"https:\\\/\\\/fimif.edu.al\\\/\",\"name\":\"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike\",\"description\":\"FIMIF, UPT Tirane\",\"publisher\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fimif.edu.al\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#organization\",\"name\":\"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike\",\"url\":\"https:\\\/\\\/fimif.edu.al\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fimif.edu.al\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Fimif-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/fimif.edu.al\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Fimif-Logo.svg\",\"width\":653,\"height\":219,\"caption\":\"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike\"},\"image\":{\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Departamenti-i-Inxhinierise-Matematike-FIMIF-UPT-100077435994252\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fimif.edu.al\\\/#\\\/schema\\\/person\\\/771075414e038199af3802af30f13da3\",\"name\":\"Gerta Lame\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026 - Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fimif.edu.al\/en\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/","og_locale":"en_GB","og_type":"article","og_title":"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026 - Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike","og_description":"Master i Shkencave ne Inxhinieri Matematike Master i Shkencave ne Inxhinieri Matematike ne Aktuaristike Master Profesional ne Analiza Sistemesh Master i Shkencave ne Inxhinieri Fizike- Profili Inxhinier Fizike Master i Shkencave ne Inxhinieri Fizike- Profili Fizikan Mjekesor","og_url":"https:\/\/fimif.edu.al\/en\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/","og_site_name":"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike","article_publisher":"https:\/\/www.facebook.com\/p\/Departamenti-i-Inxhinierise-Matematike-FIMIF-UPT-100077435994252\/","article_published_time":"2025-10-17T05:07:35+00:00","article_modified_time":"2025-10-17T08:38:28+00:00","author":"Gerta Lame","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gerta Lame","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/#article","isPartOf":{"@id":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/"},"author":{"name":"Gerta Lame","@id":"https:\/\/fimif.edu.al\/#\/schema\/person\/771075414e038199af3802af30f13da3"},"headline":"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026","datePublished":"2025-10-17T05:07:35+00:00","dateModified":"2025-10-17T08:38:28+00:00","mainEntityOfPage":{"@id":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/"},"wordCount":92,"publisher":{"@id":"https:\/\/fimif.edu.al\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/","url":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/","name":"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026 - Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike","isPartOf":{"@id":"https:\/\/fimif.edu.al\/#website"},"datePublished":"2025-10-17T05:07:35+00:00","dateModified":"2025-10-17T08:38:28+00:00","breadcrumb":{"@id":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fimif.edu.al\/njoftim-shpallen-listat-e-renditura-te-aplikanteve-per-ciklin-e-dyte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fimif.edu.al\/"},{"@type":"ListItem","position":2,"name":"Njoftim: Shpallen listat e renditura te aplikanteve ne ciklin e dyte te studimeve ne FIMIF, per vitin akademik 2025-2026"}]},{"@type":"WebSite","@id":"https:\/\/fimif.edu.al\/#website","url":"https:\/\/fimif.edu.al\/","name":"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike","description":"FIMIF, UPT Tirane","publisher":{"@id":"https:\/\/fimif.edu.al\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fimif.edu.al\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/fimif.edu.al\/#organization","name":"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike","url":"https:\/\/fimif.edu.al\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/fimif.edu.al\/#\/schema\/logo\/image\/","url":"https:\/\/fimif.edu.al\/wp-content\/uploads\/2024\/10\/Fimif-Logo.svg","contentUrl":"https:\/\/fimif.edu.al\/wp-content\/uploads\/2024\/10\/Fimif-Logo.svg","width":653,"height":219,"caption":"Fakulteti i Inxhinieris\u00eb Matematike dhe Inxhinieris\u00eb Fizike"},"image":{"@id":"https:\/\/fimif.edu.al\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Departamenti-i-Inxhinierise-Matematike-FIMIF-UPT-100077435994252\/"]},{"@type":"Person","@id":"https:\/\/fimif.edu.al\/#\/schema\/person\/771075414e038199af3802af30f13da3","name":"Gerta Lame"}]}},"_links":{"self":[{"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/posts\/8090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/comments?post=8090"}],"version-history":[{"count":3,"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/posts\/8090\/revisions"}],"predecessor-version":[{"id":8097,"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/posts\/8090\/revisions\/8097"}],"wp:attachment":[{"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/media?parent=8090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/categories?post=8090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fimif.edu.al\/en\/wp-json\/wp\/v2\/tags?post=8090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}